{"id":1100,"date":"2018-02-20T18:10:13","date_gmt":"2018-02-20T17:10:13","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=1100"},"modified":"2018-02-20T16:31:43","modified_gmt":"2018-02-20T14:31:43","slug":"%ef%83%9cune-visite-de-cooperation-de-son-excellence-lambassadeur-de-france-en-algerie-le-20-fevrier-2018","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/%ef%83%9cune-visite-de-cooperation-de-son-excellence-lambassadeur-de-france-en-algerie-le-20-fevrier-2018\/","title":{"rendered":"Une visite de coop\u00e9ration de son excellence l\u2019Ambassadeur de France en Alg\u00e9rie, le 20 f\u00e9vrier 2018"},"content":{"rendered":"<p><span style=\"color: #808080\"><span style=\"font-size: 10pt;font-family: arial, helvetica, sans-serif\">Une visite de coop\u00e9ration a \u00e9t\u00e9 effectu\u00e9e \u00e0 la Cour des comptes le 20 f\u00e9vrier 2018 par son excellence l\u2019Ambassadeur de France en Alg\u00e9rie, Monsieur Xavier DRIANCOURT.\u00a0<\/span><span style=\"font-family: arial, helvetica, sans-serif;font-size: 10pt\">Ont assist\u00e9 \u00e0 cette entrevue accord\u00e9e par \u00a0Monsieur le Pr\u00e9sident de la Cour des comptes, Messieurs le Vice-pr\u00e9sident et le Secr\u00e9taire g\u00e9n\u00e9ral. Lors de cette s\u00e9ance, Monsieur le Pr\u00e9sident a donn\u00e9 un aper\u00e7u g\u00e9n\u00e9ral sur le r\u00f4le de la Cour des comptes dans la transparence de la gestion des deniers publics. Les discussions ont port\u00e9 \u00e9galement sur les opportunit\u00e9s de coop\u00e9ration dans le domaine de l\u2019audit, ainsi que sur les conditions du d\u00e9roulement des activit\u00e9s li\u00e9es au jumelage institutionnel.<\/span><\/span><\/p>\n<p><span style=\"font-size: 10pt;font-family: arial, helvetica, sans-serif\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1105 aligncenter\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2018\/04\/photo.png\" alt=\"\" width=\"240\" height=\"159\" \/><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une visite de coop\u00e9ration a \u00e9t\u00e9 effectu\u00e9e \u00e0 la Cour des comptes le 20 f\u00e9vrier 2018 par son excellence l\u2019Ambassadeur [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,20],"tags":[],"class_list":["post-1100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-articles-francais-2"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/1100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=1100"}],"version-history":[{"count":7,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/1100\/revisions"}],"predecessor-version":[{"id":2746,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/1100\/revisions\/2746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/1141"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=1100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=1100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=1100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}