{"id":3489,"date":"2019-10-20T11:13:04","date_gmt":"2019-10-20T09:13:04","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=3489"},"modified":"2020-01-15T11:47:06","modified_gmt":"2020-01-15T10:47:06","slug":"la-cour-des-comptes-a-accueilli-la-11e-reunion-du-comite-du-plan-strategique-de-lorganisation-arabe-des-institutions-superieures-de-controle-des-finances-publiques-arabosai-du-6-au-9-octob","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/la-cour-des-comptes-a-accueilli-la-11e-reunion-du-comite-du-plan-strategique-de-lorganisation-arabe-des-institutions-superieures-de-controle-des-finances-publiques-arabosai-du-6-au-9-octob\/","title":{"rendered":"La Cour des comptes a accueilli la 11e r\u00e9union du comit\u00e9 du plan strat\u00e9gique de l\u2019Organisation arabe des institutions sup\u00e9rieures de contr\u00f4le des finances publiques (ARABOSAI), du 6 au 9 octobre 2019"},"content":{"rendered":"<p>La Cour des comptes a accueilli la onzi\u00e8me r\u00e9union du comit\u00e9 du plan strat\u00e9gique de l\u2019Organisation arabe des institutions sup\u00e9rieures de contr\u00f4le des finances publiques (ARABOSAI), du 6 au 9 octobre 2019 \u00e0 l\u2019H\u00f4tel El Aurassi.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1152 aligncenter\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2019\/12\/\u0627\u0633\u062a\u0636\u0627\u0641\u0629-\u0645\u062c\u0644\u0633-\u0627\u0644\u0645\u062d\u0627\u0633\u0628\u0629-\u0627\u0644\u062c\u0632\u0627\u0626\u0631\u064a-\u0644\u0644\u0627\u062c\u062a\u0645\u0627\u0639-\u0627\u0644\u062d\u0627\u062f\u064a-\u0639\u0634\u0631-\u0644\u0644\u062c\u0646\u0629-\u0627\u0644\u0645\u062e\u0637\u0637-\u0627\u0644\u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a-\u0644\u0644\u0623\u0631\u0627\u0628\u0648\u0633\u0627\u064a-1.png\" alt=\"\" width=\"300\" height=\"217\" \/><\/a><\/p>\n<p>En sus de la Cour des comptes alg\u00e9rienne et du repr\u00e9sentant du Secr\u00e9tariat g\u00e9n\u00e9ral de l\u2019ARABOSAI, 16 institutions sup\u00e9rieures de contr\u00f4le (ISC) arabes ont particip\u00e9 \u00e0 cette r\u00e9union, en l\u2019occurrence la R\u00e9publique d\u2019Irak, la R\u00e9publique arabe d\u2019\u00c9gypte, l\u2019\u00c9tat de Libye, l\u2019\u00c9tat du Qatar, le Royaume d\u2019Arabie saoudite et l\u2019\u00c9tat du Kowe\u00eft.<br \/>\nLa r\u00e9union a abord\u00e9 un certain nombre de th\u00e8mes dont les plus importants sont ceux li\u00e9s \u00e0 l\u2019\u00e9tude des plans op\u00e9rationnels des structures de l\u2019Organisation pour 2020-2022 et leur coh\u00e9rence avec les objectifs contenus dans le plan strat\u00e9gique de l\u2019Organisation. Ladite r\u00e9union a \u00e9galement examin\u00e9 les premiers r\u00e9sultats de la mise en \u0153uvre des objectifs du plan op\u00e9rationnel de 2019, par les comit\u00e9s et le Secr\u00e9tariat g\u00e9n\u00e9ral.<br \/>\nPar ailleurs, le comit\u00e9 du plan strat\u00e9gique a \u00e9labor\u00e9 un plan visant l\u2019analyse des r\u00e9sultats et l\u2019\u00e9laboration du rapport qui sera pr\u00e9sent\u00e9 au conseil ex\u00e9cutif lors de sa prochaine r\u00e9union. De m\u00eame, un rapport d\u00e9taill\u00e9 sur les r\u00e9sultats des travaux du comit\u00e9 durant les trois derni\u00e8res ann\u00e9es sera pr\u00e9sent\u00e9 \u00e0 la prochaine assembl\u00e9e g\u00e9n\u00e9rale de l\u2019organisation, pr\u00e9vue au mois de novembre 2019.<br \/>\nEnfin, des recommandations constructives ont \u00e9t\u00e9 formul\u00e9es et seront pr\u00e9sent\u00e9es au conseil ex\u00e9cutif de l\u2019organisation lors de sa prochaine r\u00e9union.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cour des comptes a accueilli la onzi\u00e8me r\u00e9union du comit\u00e9 du plan strat\u00e9gique de l\u2019Organisation arabe des institutions sup\u00e9rieures [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":3488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-3489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/3489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=3489"}],"version-history":[{"count":3,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/3489\/revisions"}],"predecessor-version":[{"id":3613,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/3489\/revisions\/3613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/3488"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=3489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=3489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=3489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}