{"id":5198,"date":"2021-10-03T16:07:33","date_gmt":"2021-10-03T14:07:33","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=5198"},"modified":"2021-10-17T16:39:36","modified_gmt":"2021-10-17T14:39:36","slug":"participation-a-une-reunion-de-consultation-avec-le-fonds-monetaire-international","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-a-une-reunion-de-consultation-avec-le-fonds-monetaire-international\/","title":{"rendered":"Participation \u00e0 une r\u00e9union consacr\u00e9e \u00e0 la pr\u00e9sentation des travaux analytiques sur \u00ab la gouvernance \u00bb par Fonds mon\u00e9taire international"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Conform\u00e9ment aux dispositions de l\u2019article IV des Statuts du Fonds mon\u00e9taire international (FMI), et dans le cadre des consultations entre l\u2019Alg\u00e9rie et ce dernier, une d\u00e9l\u00e9gation de la Cour des comptes pr\u00e9sid\u00e9e par M. Abdelkader BENMAROUF, Pr\u00e9sident de la Cour, et compos\u00e9e de MM. Mohamed Fouad NACIR, Vice-pr\u00e9sident, Med Salim BENAMMAR, Secr\u00e9taire g\u00e9n\u00e9ral, Ikhlef YESSAD, Rapporteur g\u00e9n\u00e9ral charg\u00e9 du rapport annuel, et Nabila MAACHOU, Directrice d\u2019\u00e9tudes, a particip\u00e9 le jeudi 30 septembre 2021 \u00e0 une r\u00e9union tenue par visioconf\u00e9rence avec des experts du FMI, et \u00e0 laquelle ont assist\u00e9 les repr\u00e9sentants des institutions concern\u00e9es par la gouvernance, ayant particip\u00e9 aux consultations.<\/p>\n<p>La r\u00e9union a \u00e9t\u00e9 consacr\u00e9e \u00e0 la pr\u00e9sentation des travaux analytiques sur la gouvernance en Alg\u00e9rie, et qui ont port\u00e9 sur les axes suivants :<\/p>\n<p>&#8211; l\u2019\u00e9tat des lieux de la corruption en Alg\u00e9rie\u00a0;<\/p>\n<p>&#8211; l\u2019\u00e9valuation du dispositif de lutte contre la corruption et le blanchiment d\u2019argent en Alg\u00e9rie\u00a0;<\/p>\n<p>&#8211; la gouvernance \u00e9conomique : forces, faiblesses, et pistes d\u2019am\u00e9lioration dans le domaine des finances publiques, de la Banque centrale et de l\u2019environnement des affaires.<\/p>\n<p>Les experts du FMI ont \u00e9galement salu\u00e9, dans leurs interventions, le renforcement de l\u2019ind\u00e9pendance de la Cour des comptes \u00e0 travers la nouvelle constitution.<\/p>\n<p><a href=\"https:\/\/www.ccomptes.dz\/fr\/actualite\/participation-de-la-cour-des-comptes-a-une-reunion-de-consultation-avec-le-fonds-monetaire-international\/attachment\/img-20210930-wa0003\/\" rel=\"attachment wp-att-5191\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5191 \" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0003-1024x576.jpg\" alt=\"\" width=\"696\" height=\"391\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0003-1024x576.jpg 1024w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0003-300x169.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0003-768x432.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0003.jpg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/a> <a href=\"https:\/\/www.ccomptes.dz\/fr\/actualite\/participation-de-la-cour-des-comptes-a-une-reunion-de-consultation-avec-le-fonds-monetaire-international\/attachment\/img-20210930-wa0005\/\" rel=\"attachment wp-att-5190\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5190 \" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0005-1024x576.jpg\" alt=\"\" width=\"698\" height=\"393\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0005-1024x576.jpg 1024w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0005-300x169.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0005-768x432.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2021\/10\/IMG-20210930-WA0005.jpg 1280w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Conform\u00e9ment aux dispositions de l\u2019article IV des Statuts du Fonds mon\u00e9taire international (FMI), et dans le cadre des consultations [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=5198"}],"version-history":[{"count":3,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5198\/revisions"}],"predecessor-version":[{"id":5207,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5198\/revisions\/5207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/5184"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=5198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=5198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=5198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}