{"id":5302,"date":"2021-11-16T15:50:03","date_gmt":"2021-11-16T14:50:03","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=5302"},"modified":"2021-11-17T08:02:04","modified_gmt":"2021-11-17T07:02:04","slug":"debut-des-travaux-du-seminaire-de-formation-a-distance-portant-sur-laudit-des-parties-beneficiant-du-soutien-financier-de-letat-organise-par-la-cour-des-comptes-du-8-a","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/debut-des-travaux-du-seminaire-de-formation-a-distance-portant-sur-laudit-des-parties-beneficiant-du-soutien-financier-de-letat-organise-par-la-cour-des-comptes-du-8-a\/","title":{"rendered":"D\u00e9but des travaux du s\u00e9minaire de formation \u00e0 distance portant sur \u00ab L\u2019audit des parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat \u00bb, organis\u00e9 par la Cour des comptes du 8 au 11 novembre 2021"},"content":{"rendered":"<p>La Cour des comptes a organis\u00e9 aujourd\u2019hui en collaboration avec l\u2019Organisation arabe des Institutions Sup\u00e9rieures de Contr\u00f4le (ARABOSAI), un s\u00e9minaire de formation \u00e0 distance sur le th\u00e8me \u00ab L\u2019audit des parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat \u00bb. Ce dernier se d\u00e9roulera sur quatre jours du 8 au 11 novembre 2021.<\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019ouverture du s\u00e9minaire a \u00e9t\u00e9 assur\u00e9e par une allocution de M. Abdelkader BENMAROUF, Pr\u00e9sident de la Cour des comptes, \u00e0 travers laquelle il a soulign\u00e9 l\u2019importance cruciale du contr\u00f4le exerc\u00e9 par les Institutions Sup\u00e9rieures de Contr\u00f4le (ISC) sur les parties qui b\u00e9n\u00e9ficient du soutien financier de l\u2019\u00c9tat.<\/p>\n<p>&nbsp;<\/p>\n<p>Quatre formateurs de la Cour des comptes assurent l\u2019animation de cet \u00e9v\u00e8nement, auquel participent 29 repr\u00e9sentants des ISC des pays arabes : la Jordanie, le Bahre\u00efn, l\u2019Alg\u00e9rie, l\u2019Arabie saoudite, le Sultanat d\u2019Oman, le Soudan, la Syrie, l\u2019Irak, la Palestine, le Qatar, le Kowe\u00eft, la Libye, l\u2019\u00c9gypte, le Maroc, la Mauritanie, et le Y\u00e9men.<\/p>\n<p>&nbsp;<\/p>\n<p>Le th\u00e8me du s\u00e9minaire s\u2019articule autour des axes suivants :<\/p>\n<p>&#8211; Le r\u00f4le des parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat dans la mise en \u0153uvre des politiques publiques ;<\/p>\n<p>&#8211; Les formes et l\u2019importance du soutien financier accord\u00e9 par l\u2019\u00c9tat ;<\/p>\n<p>&#8211; Les proc\u00e9dures d\u2019audit des parties b\u00e9n\u00e9ficiant du soutien ;<\/p>\n<p>&#8211; Le contr\u00f4le de la Cour des comptes sur les parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2021\/11\/1-2.jpg\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2021\/11\/1-1.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Cour des comptes a organis\u00e9 aujourd\u2019hui en collaboration avec l\u2019Organisation arabe des Institutions Sup\u00e9rieures de Contr\u00f4le (ARABOSAI), un s\u00e9minaire [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5299,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=5302"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5302\/revisions"}],"predecessor-version":[{"id":5303,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5302\/revisions\/5303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/5299"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=5302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=5302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=5302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}