{"id":5349,"date":"2021-11-16T15:14:34","date_gmt":"2021-11-16T14:14:34","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=5349"},"modified":"2021-11-16T15:14:34","modified_gmt":"2021-11-16T14:14:34","slug":"apres-cinq-5-ans-dun-programme-de-partenariat-avec-sept-7-isc-arabes-dont-la-cour-des-comptes","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/apres-cinq-5-ans-dun-programme-de-partenariat-avec-sept-7-isc-arabes-dont-la-cour-des-comptes\/","title":{"rendered":"Apr\u00e8s cinq (5) ans d\u2019un programme de partenariat avec sept (7) ISC arabes, dont la Cour des comptes"},"content":{"rendered":"<p><strong>Cl\u00f4ture du programme de coop\u00e9ration internationale \u00ab\u00a0Sharaka\u00a0\u00bb avec la Cour des comptes des Pays-Bas<\/strong><\/p>\n<p>L\u2019actuel programme de coop\u00e9ration internationale \u00ab\u00a0Sharaka\u00a0\u00bb entre la Cour des comptes n\u00e9erlandaise et les ISC arabes concern\u00e9s s\u2019est achev\u00e9 les 27 et 28 octobre 2021. \u00c0 cette occasion, la Cour a organis\u00e9 des r\u00e9unions \u00e0 distance avec les repr\u00e9sentants des ISC arabes participant \u00e0 ce programme.<\/p>\n<p>Ci-apr\u00e8s, le communiqu\u00e9 de presse de la Cour des comptes des Pays-Bas relatif \u00e0 la cl\u00f4ture du programme \u00ab\u00a0Sharaka\u00a0\u00bb, et \u00e0 la mise en place d\u2019un nouveau programme de coop\u00e9ration.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cl\u00f4ture du programme de coop\u00e9ration internationale \u00ab\u00a0Sharaka\u00a0\u00bb avec la Cour des comptes des Pays-Bas L\u2019actuel programme de coop\u00e9ration internationale \u00ab\u00a0Sharaka\u00a0\u00bb [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5274,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=5349"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5349\/revisions"}],"predecessor-version":[{"id":5350,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5349\/revisions\/5350"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/5274"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=5349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=5349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=5349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}