{"id":5374,"date":"2021-11-17T08:20:05","date_gmt":"2021-11-17T07:20:05","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=5374"},"modified":"2021-11-17T14:16:46","modified_gmt":"2021-11-17T13:16:46","slug":"poursuite-des-travaux-du-seminaire-de-formation-a-distance-dans-sa-quatrieme-et-derniere-journee-sur-laudit-des-parties-beneficiant-du-soutien-financier-de-letat","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/poursuite-des-travaux-du-seminaire-de-formation-a-distance-dans-sa-quatrieme-et-derniere-journee-sur-laudit-des-parties-beneficiant-du-soutien-financier-de-letat\/","title":{"rendered":"Poursuite des travaux du s\u00e9minaire de formation \u00e0 distance dans sa quatri\u00e8me et derni\u00e8re journ\u00e9e, sur \u00ab L\u2019audit des parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat \u00bb"},"content":{"rendered":"<p>Les travaux du s\u00e9minaire de formation \u00e0 distance sur \u00ab L\u2019audit des parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat \u00bb se poursuivent pour la quatri\u00e8me et derni\u00e8re journ\u00e9e, qui a \u00e9t\u00e9 consacr\u00e9e au th\u00e8me portant sur \u00ab Le contr\u00f4le de la Cour des comptes sur les parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat : cas du minist\u00e8re de la Jeunesse et des Sports \u00bb.<\/p>\n<p>Les axes principaux de la troisi\u00e8me journ\u00e9e du s\u00e9minaire de formation sont les suivants :<\/p>\n<p>&#8211; Le contr\u00f4le a posteriori de la Cour des comptes ;<\/p>\n<p>&#8211; La cartographie des risques li\u00e9s aux finances des entit\u00e9s b\u00e9n\u00e9ficiant du soutien ;<\/p>\n<p>&#8211; Les r\u00e9sultats de l\u2019op\u00e9ration d\u2019audit effectu\u00e9e par la Cour des comptes ;<\/p>\n<p>&#8211; Les recommandations formul\u00e9es ;<\/p>\n<p>&#8211; Les d\u00e9fis et les difficult\u00e9s rencontr\u00e9s au cours des audits des parties b\u00e9n\u00e9ficiant du soutien de l\u2019\u00c9tat.<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/Courdescomptesdz\/videos\/616884369466389\" target=\"_blank\" rel=\"noopener\">Ci-apr\u00e8s, un r\u00e9sum\u00e9 de l\u2019intervention de M. Ahmed SAADI, Magistrat \u00e0 la Cour des comptes, intitul\u00e9e \u00ab Le contr\u00f4le de la Cour des comptes sur les parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat : cas du minist\u00e8re de la Jeunesse et des Sports \u00bb, pr\u00e9sent\u00e9e au cours de ce s\u00e9minaire.<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2021\/11\/17-11-2-1.png\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les travaux du s\u00e9minaire de formation \u00e0 distance sur \u00ab L\u2019audit des parties b\u00e9n\u00e9ficiant du soutien financier de l\u2019\u00c9tat \u00bb [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=5374"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5374\/revisions"}],"predecessor-version":[{"id":5375,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5374\/revisions\/5375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/5372"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=5374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=5374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=5374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}