{"id":5797,"date":"2022-03-15T14:19:37","date_gmt":"2022-03-15T13:19:37","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=5797"},"modified":"2022-03-15T14:19:37","modified_gmt":"2022-03-15T13:19:37","slug":"participation-a-un-atelier-a-distance-sur-la-lutte-contre-la-desertification-la-securite-alimentaire-et-le-developpement-durable","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-a-un-atelier-a-distance-sur-la-lutte-contre-la-desertification-la-securite-alimentaire-et-le-developpement-durable\/","title":{"rendered":"Participation \u00e0 un atelier \u00e0 distance sur \u00ab la lutte contre la d\u00e9sertification, la s\u00e9curit\u00e9 alimentaire et le d\u00e9veloppement durable \u00bb"},"content":{"rendered":"<p style=\"text-align: justify\">Mme Fella Houamria, magistrat, et M. Abderazzak Hamidi, v\u00e9rificateur financier \u00e0 la 5<sup>e<\/sup> Chambre, ont particip\u00e9 \u00e0 distance du 16 au 18 f\u00e9vrier 2022 \u00e0 un atelier sur \u00ab la lutte contre la d\u00e9sertification, la s\u00e9curit\u00e9 alimentaire et le d\u00e9veloppement durable\u00a0\u00bb, organis\u00e9 par l\u2019ISC de l\u2019Inde en coop\u00e9ration avec le Centre international pour l\u2019audit environnemental et le d\u00e9veloppement durable (iCED) et le Groupe de travail de l\u2019INTOSAI sur l\u2019audit environnementale (WGEA).<\/p>\n<p style=\"text-align: justify\">Les principaux th\u00e8mes de cet atelier \u00e9taient :<\/p>\n<ul style=\"text-align: justify\">\n<li>Les d\u00e9fis de la communaut\u00e9 internationale en mati\u00e8re de s\u00e9curit\u00e9 alimentaire et de lutte contre la d\u00e9sertification, dans le cadre des Objectifs de d\u00e9veloppement durable (ODD) ;<\/li>\n<li>La m\u00e9thodologie sur laquelle les organisations internationales et nationales s\u2019appuient dans l\u2019\u00e9valuation des performances li\u00e9es aux ODD li\u00e9s \u00e0 la lutte contre la d\u00e9sertification et la s\u00e9curit\u00e9 alimentaire.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Au cours de cet atelier, des exp\u00e9riences ont \u00e9t\u00e9 \u00e9chang\u00e9es entre les participants en \u00e0 travers la pr\u00e9sentation de processus d\u2019audit sur le sujet.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/03\/15-3-4-1.jpg\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/03\/15-3-4-2.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mme Fella Houamria, magistrat, et M. Abderazzak Hamidi, v\u00e9rificateur financier \u00e0 la 5e Chambre, ont particip\u00e9 \u00e0 distance du 16 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":5798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=5797"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5797\/revisions"}],"predecessor-version":[{"id":5800,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/5797\/revisions\/5800"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/5798"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=5797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=5797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=5797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}