{"id":6074,"date":"2022-04-26T11:47:19","date_gmt":"2022-04-26T09:47:19","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=6074"},"modified":"2022-04-26T11:47:19","modified_gmt":"2022-04-26T09:47:19","slug":"reunion-du-comite-des-programmes-et-des-rapports-9","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/reunion-du-comite-des-programmes-et-des-rapports-9\/","title":{"rendered":"R\u00e9union du Comit\u00e9 des programmes et des rapports"},"content":{"rendered":"<p><span style=\"color: #000000\">Le Comit\u00e9 des programmes et des rapports s\u2019est r\u00e9uni le mercredi 20 avril 2022 par visioconf\u00e9rence, sous la pr\u00e9sidence de M. Abdelkader BENMAROUF, Pr\u00e9sident de la Cour des comptes, en vue d\u2019examiner et d\u2019adopter le projet d\u2019une note d\u2019insertion au rapport annuel 2022, pr\u00e9sent\u00e9 par la Chambre territoriale de Tlemcen.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/04\/rrrrrrr.jpg\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Comit\u00e9 des programmes et des rapports s\u2019est r\u00e9uni le mercredi 20 avril 2022 par visioconf\u00e9rence, sous la pr\u00e9sidence de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=6074"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6074\/revisions"}],"predecessor-version":[{"id":6076,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6074\/revisions\/6076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/6075"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=6074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=6074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=6074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}