{"id":6258,"date":"2022-06-23T15:42:05","date_gmt":"2022-06-23T13:42:05","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=6258"},"modified":"2022-06-23T15:42:05","modified_gmt":"2022-06-23T13:42:05","slug":"poursuite-de-la-formation-portant-sur-la-communication-strategique-et-operationnelle-2","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/poursuite-de-la-formation-portant-sur-la-communication-strategique-et-operationnelle-2\/","title":{"rendered":"Poursuite de la formation portant sur la communication strat\u00e9gique et op\u00e9rationnelle"},"content":{"rendered":"<p style=\"text-align: left\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">Dans le cadre du programme de coop\u00e9ration avec le Corps des volontaires des services financiers (FSVC), le groupe de communication compos\u00e9 de Mmes et M. Hocine Benssam, directeur du d\u00e9partement des \u00e9tudes et du traitement de l\u2019information, Nabila Maachou, directrice d\u2019\u00e9tudes, Sana Lebouzada, chef d\u2019\u00e9tudes, et Nawal Chebira, magistrat \u00e0 la 7<sup>e<\/sup> Chambre, a particip\u00e9 aujourd\u2019hui 6 juin 2022 \u00e0 une session de formation \u00e0 distance portant sur \u00ab la communication strat\u00e9gique et op\u00e9rationnelle \u00bb.<\/span><\/p>\n<p style=\"text-align: left\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">Cette session de formation, anim\u00e9e par MM. Mourad Bengassouma et Scott Dykema, experts aupr\u00e8s du FSVC, vise le renforcement des capacit\u00e9s de communication avec les m\u00e9dias.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/06\/1111.png\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du programme de coop\u00e9ration avec le Corps des volontaires des services financiers (FSVC), le groupe de communication [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=6258"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6258\/revisions"}],"predecessor-version":[{"id":6260,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6258\/revisions\/6260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/6259"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=6258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=6258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=6258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}