{"id":6352,"date":"2022-10-03T12:12:32","date_gmt":"2022-10-03T10:12:32","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=6352"},"modified":"2022-10-03T12:12:32","modified_gmt":"2022-10-03T10:12:32","slug":"seminaire-de-lancement-du-projet-de-jumelage-portant-sur-le-renforcement-des-capacites-institutionnelles-et-professionnelles-de-la-cour-des-comptes","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/seminaire-de-lancement-du-projet-de-jumelage-portant-sur-le-renforcement-des-capacites-institutionnelles-et-professionnelles-de-la-cour-des-comptes\/","title":{"rendered":"S\u00e9minaire de lancement du projet de jumelage portant sur le renforcement des capacit\u00e9s institutionnelles et professionnelles de la Cour des comptes"},"content":{"rendered":"<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">La Cour des comptes a organis\u00e9, en partenariat avec la d\u00e9l\u00e9gation de l\u2019Union europ\u00e9enne \u00e0 Alger, le mardi 27 septembre 2022 \u00e0 l\u2019h\u00f4tel El Aurassi, le s\u00e9minaire de lancement du projet de jumelage portant sur \u00ab le renforcement des capacit\u00e9s institutionnelles et professionnelles de la Cour des comptes \u00bb.<\/span><\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/10\/2.jpg\" \/><\/p>\n<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">Ce projet de jumelage s\u2019inscrit dans le cadre du programme de Facilit\u00e9 d\u2019appui aux priorit\u00e9s du Partenariat Alg\u00e9rie-Union europ\u00e9enne \u00ab FAPP \u00bb, pour un montant de 1.000.000 d\u2019euros, et conclu avec un consortium constitu\u00e9 de la Cour des comptes fran\u00e7aise et du Tribunal de contas portugais, il s\u2019\u00e9tale sur une p\u00e9riode de 24 mois (mars 2022-mars 2024).<\/span><\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/10\/1.jpg\" \/><\/p>\n<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">La c\u00e9r\u00e9monie de lancement du projet de jumelage a \u00e9t\u00e9 pr\u00e9sid\u00e9e par M. Abdelkader BENMAROUF Pr\u00e9sident de la Cour des comptes alg\u00e9rienne, en pr\u00e9sence de hauts responsables de l\u2019\u00c9tat, d\u2019ambassadeurs, d\u2019experts, de pr\u00e9sidents d\u2019organisations professionnelles et des cadres et magistrats de la Cour des comptes.<\/span><\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/10\/3.jpg\" \/><\/p>\n<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">Dans son allocution d\u2019ouverture, M. Abdelkader BENMAROUF Pr\u00e9sident de la Cour des comptes, a pr\u00e9cis\u00e9 que ce projet de jumelage vise \u00e0 consolider les capacit\u00e9s de la Cour des comptes en mati\u00e8re de certification des comptes de l\u2019\u00c9tat, d\u2019audit de performance et d\u2019\u00e9valuation des politiques publiques, et ce, en harmonie avec les normes et les meilleures pratiques internationales.<\/span><\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/10\/4.jpg\" \/><\/p>\n<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">Il a par ailleurs soulign\u00e9 que la loi organique n\u00b018-15 du 2 septembre 2018 relative aux lois de finances, qui sera mise en \u0153uvre en 2023, a profond\u00e9ment r\u00e9form\u00e9 le cadre budg\u00e9taire et comptable de l\u2019\u00c9tat, puisqu\u2019elle entend instaurer une logique de performance et une culture de r\u00e9sultat, et donc une efficacit\u00e9 et une efficience plus accrues dans la gestion publique.<\/span><\/p>\n<p style=\"text-align: left\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/10\/5.jpg\" \/><\/p>\n<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">Aussi, et toujours dans cette optique, la Cour des comptes s\u2019attelle aujourd\u2019hui \u00e0 s\u2019adapter aux r\u00e9formes en cours orient\u00e9es vers la performance et les r\u00e9sultats en mati\u00e8re de gestion budg\u00e9taire, d\u2019une part, et marqu\u00e9es par le passage d\u2019une comptabilit\u00e9 de caisse \u00e0 une comptabilit\u00e9 de type patrimonial bas\u00e9e sur le principe des droits constat\u00e9s, d\u2019autre part.<\/span><\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">Pour y parvenir , le Pr\u00e9sident de la Cour des comptes M. Abdelkader BENMAROUF a exhort\u00e9 et invit\u00e9 les experts ainsi que les professionnels du contr\u00f4le \u00e0 ne m\u00e9nager aucun effort pour l\u2019atteinte des objectifs trac\u00e9s et la r\u00e9ussite de ce projet d\u2019envergure, qui permettra in\u00e9luctablement \u00e0 la Cour de s\u2019approprier les techniques modernes de l\u2019audit, et de remplir pleinement \u00e0 l\u2019horizon 2025, son r\u00f4le de commissaire aux comptes de l\u2019\u00c9tat.<\/span><\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\"><span style=\"color: #000000;font-family: 'times new roman', times, serif\">De m\u00eame, il a souhait\u00e9 que tous les partenaires du Minist\u00e8re des Finances et des autres d\u00e9partements minist\u00e9riels, \u0153uvrent dans le sens d\u2019une relation interactive et p\u00e9renne, b\u00e2tie sur le partage des connaissances et l\u2019entraide avec la Cour des comptes, tant au niveau des services gestionnaires que ceux charg\u00e9s de la production des comptes de l\u2019\u00c9tat.<\/span><\/p>\n<p style=\"text-align: left\">\n<p style=\"text-align: left\">\n","protected":false},"excerpt":{"rendered":"<p>La Cour des comptes a organis\u00e9, en partenariat avec la d\u00e9l\u00e9gation de l\u2019Union europ\u00e9enne \u00e0 Alger, le mardi 27 septembre [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=6352"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6352\/revisions"}],"predecessor-version":[{"id":6358,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6352\/revisions\/6358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/6354"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=6352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=6352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=6352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}