{"id":6485,"date":"2022-11-09T15:28:40","date_gmt":"2022-11-09T14:28:40","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=6485"},"modified":"2022-11-09T15:36:15","modified_gmt":"2022-11-09T14:36:15","slug":"participation-aux-travaux-de-la-24e-session-de-lassemblee-generale-de-lintosai","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-aux-travaux-de-la-24e-session-de-lassemblee-generale-de-lintosai\/","title":{"rendered":"Participation aux travaux de la 24e session de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019INTOSAI"},"content":{"rendered":"<p style=\"text-align: justify\">Une d\u00e9l\u00e9gation de la Cour des comptes pr\u00e9sid\u00e9e par M. Mohamed Fouad Nacir, Vice-pr\u00e9sident de la Cour, et compos\u00e9e de M. Ahmed Guettai, Pr\u00e9sident de la 3<sup>e<\/sup> Chambre, et Mme Nabila Maachou, Directrice d\u2019\u00e9tudes, participe aux travaux de la 24<sup>e<\/sup> session de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale de l\u2019Organisation internationale des institutions sup\u00e9rieures de contr\u00f4le des finances publiques (INTOSAI), durant la p\u00e9riode du 8 au 11 novembre, \u00e0 Rio de Janeiro au Br\u00e9sil.<\/p>\n<p style=\"text-align: justify\">L\u2019ordre du jour de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale, comprend, entre autre, les points suivants :<\/p>\n<p style=\"text-align: justify\">&#8211; \u00a0Rapport du Secr\u00e9taire g\u00e9n\u00e9ral\u00a0de l\u2019Organisation\u00a0;<\/p>\n<p style=\"text-align: justify\">&#8211; \u00a0Plan strat\u00e9gique de l\u2019INTOSAI 2023-2028\u00a0;<\/p>\n<p style=\"text-align: justify\">&#8211; Rapport de la Revue internationale de la v\u00e9rification des comptes publics\u00a0;<\/p>\n<p style=\"text-align: justify\">&#8211; \u00a0Rapport des auditeurs de l\u2019INTOSAI\u00a0;<\/p>\n<p style=\"text-align: justify\">&#8211; Rapports des organisations r\u00e9gionales des institutions sup\u00e9rieures de contr\u00f4le des finances publiques, des organisations internationales et des institutions financi\u00e8res internationales concern\u00e9es.<\/p>\n<p style=\"text-align: justify\">&#8211; Les rapports du\u00a0Comit\u00e9 de surveillance sur les questions \u00e9mergentes (SCEI), de la Commission des normes professionnelles (PSC), de la Commission charg\u00e9e du renforcement des capacit\u00e9s (CBC), et de la Commission des affaires politiques, financi\u00e8res et administratives (PFAC)\u00a0;<\/p>\n<p style=\"text-align: justify\">&#8211; Rapport de l\u2019Initiative de d\u00e9veloppement de l\u2019INTOSAI (IDI).<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/11\/09-11-2022-1-1.png\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/11\/09-11-2022-1-2.jpg\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une d\u00e9l\u00e9gation de la Cour des comptes pr\u00e9sid\u00e9e par M. Mohamed Fouad Nacir, Vice-pr\u00e9sident de la Cour, et compos\u00e9e de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6485","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=6485"}],"version-history":[{"count":2,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6485\/revisions"}],"predecessor-version":[{"id":6497,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6485\/revisions\/6497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/6487"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=6485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=6485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=6485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}