{"id":6538,"date":"2022-12-05T08:45:40","date_gmt":"2022-12-05T07:45:40","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=6538"},"modified":"2022-12-05T08:45:40","modified_gmt":"2022-12-05T07:45:40","slug":"session-de-formation-dans-le-domaine-de-la-communication-strategique-et-operationnelle","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/session-de-formation-dans-le-domaine-de-la-communication-strategique-et-operationnelle\/","title":{"rendered":"Session de formation dans le domaine de la communication strat\u00e9gique et op\u00e9rationnelle"},"content":{"rendered":"<p style=\"text-align: left\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">Dans le cadre du programme de coop\u00e9ration avec le Corps des volontaires des services financiers (FSVC), le groupe de communication compos\u00e9 de Mmes et M. Hocine Benssam, directeur du d\u00e9partement des \u00e9tudes et du traitement de l\u2019information, Nabila Maachou, directrice d\u2019\u00e9tudes, Sana Lebouzada, chef d\u2019\u00e9tudes, et Nawal Chebira, magistrat \u00e0 la 7e Chambre, a particip\u00e9 le jeudi 1er d\u00e9cembre 2022, \u00e0 une session de formation \u00e0 distance portant sur \u00ab l\u2019organisation des conf\u00e9rences de presse \u00bb.<\/span><\/p>\n<p style=\"text-align: left\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">Cette session de formation, anim\u00e9e par MM. Mourad Bengassouma et Scott Dykema, experts aupr\u00e8s du FSVC, vise le renforcement des capacit\u00e9s de communication avec les m\u00e9dias.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2022\/12\/1.png\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du programme de coop\u00e9ration avec le Corps des volontaires des services financiers (FSVC), le groupe de communication [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=6538"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6538\/revisions"}],"predecessor-version":[{"id":6540,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6538\/revisions\/6540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/6539"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=6538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=6538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=6538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}