{"id":6704,"date":"2023-01-25T09:31:30","date_gmt":"2023-01-25T08:31:30","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=6704"},"modified":"2023-01-25T09:31:30","modified_gmt":"2023-01-25T08:31:30","slug":"reunion-du-president-de-la-cour-des-comptes-avec-le-president-magistrats-verificateurs-financiers-et-greffiers-de-la-premiere-chambre","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/reunion-du-president-de-la-cour-des-comptes-avec-le-president-magistrats-verificateurs-financiers-et-greffiers-de-la-premiere-chambre\/","title":{"rendered":"R\u00e9union du Pr\u00e9sident de la Cour des comptes avec le pr\u00e9sident, magistrats, v\u00e9rificateurs financiers et greffiers de la premi\u00e8re chambre"},"content":{"rendered":"<p style=\"text-align: left\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">Le Pr\u00e9sident de la Cour des comptes, M. Abdelkader BENMAROUF, a tenu une r\u00e9union le 23 janvier 2023 avec le Pr\u00e9sident de la premi\u00e8re chambre M. Abdelatif AZIEZ, et les magistrats, v\u00e9rificateurs financiers et greffiers de la m\u00eame chambre, en pr\u00e9sence de M. Med Fouad NACIR, Vice-Pr\u00e9sident et Mme Nabila MAACHOU, Directrice d\u2019\u00e9tudes.<\/span><\/p>\n<p style=\"text-align: left\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">L\u2019objet de cette r\u00e9union, visant le renforcement de la communication interne au sein de la Cour des comptes, est de rappeler les priorit\u00e9s de l\u2019institution pour 2023, et de poursuivre l\u2019am\u00e9lioration du professionnalisme des auditeurs en s\u2019appuyant sur les normes de contr\u00f4le et les guides m\u00e9thodologiques.<\/span><\/p>\n<p style=\"text-align: left\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">Le Pr\u00e9sident a \u00e9galement \u00e9cout\u00e9 \u00e0 leurs pr\u00e9occupations et propositions en vue d\u2019am\u00e9liorer la qualit\u00e9 du travail de contr\u00f4le et d\u2019accomplir pleinement les missions de la Cour des comptes.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2023\/01\/pre.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la Cour des comptes, M. Abdelkader BENMAROUF, a tenu une r\u00e9union le 23 janvier 2023 avec le [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":6705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=6704"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6704\/revisions"}],"predecessor-version":[{"id":6706,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/6704\/revisions\/6706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/6705"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=6704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=6704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=6704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}