{"id":7341,"date":"2023-10-02T16:06:07","date_gmt":"2023-10-02T14:06:07","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=7341"},"modified":"2023-10-02T16:06:07","modified_gmt":"2023-10-02T14:06:07","slug":"participation-a-un-webinaire-portant-sur-lamelioration-de-la-performance-des-entreprises-publiques-adopter-un-cadre-pour-identifier-et-encourager-les-reformes-des-entreprises-publiqu","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-a-un-webinaire-portant-sur-lamelioration-de-la-performance-des-entreprises-publiques-adopter-un-cadre-pour-identifier-et-encourager-les-reformes-des-entreprises-publiqu\/","title":{"rendered":"Participation \u00e0 un webinaire portant sur \u00ab l\u2019am\u00e9lioration de la performance des entreprises publiques : adopter un cadre pour identifier et encourager les r\u00e9formes des entreprises publiques dans les pays arabes \u00bb  Mme Nassima Meddour, Magistrat \u00e0 la 8e Chambre, participe Aujourd\u2019hui 2 octobre 2023, \u00e0 un webinaire portant sur \u00ab l\u2019am\u00e9lioration de la performance des entreprises publiques : adopter un cadre pour identifier et promouvoir les r\u00e9formes des entreprises publiques dans les pays arabes \u00bb, organis\u00e9 par le Fonds mon\u00e9taire arabe en partenariat avec le Groupe de la Banque mondiale.  Ce webinaire discutera du cadre propos\u00e9 par la Banque mondiale afin de r\u00e9former le secteur \u00e9conomique public, des axes de r\u00e9formes bas\u00e9s sur les exp\u00e9riences et les le\u00e7ons retenues de la r\u00e9gion arabe, dans le but d&rsquo;encourager la r\u00e9forme des entreprises publiques, d&rsquo;am\u00e9liorer leur performance et leur contribution au d\u00e9veloppement \u00e9conomique."},"content":{"rendered":"<p>Mme Nassima Meddour, Magistrat \u00e0 la 8e Chambre, participe Aujourd\u2019hui 2 octobre 2023, \u00e0 un webinaire portant sur \u00ab l\u2019am\u00e9lioration de la performance des entreprises publiques : adopter un cadre pour identifier et promouvoir les r\u00e9formes des entreprises publiques dans les pays arabes \u00bb, organis\u00e9 par le Fonds mon\u00e9taire arabe en partenariat avec le Groupe de la Banque mondiale.<\/p>\n<p>Ce webinaire discutera du cadre propos\u00e9 par la Banque mondiale afin de r\u00e9former le secteur \u00e9conomique public, des axes de r\u00e9formes bas\u00e9s sur les exp\u00e9riences et les le\u00e7ons retenues de la r\u00e9gion arabe, dans le but d&rsquo;encourager la r\u00e9forme des entreprises publiques, d&rsquo;am\u00e9liorer leur performance et leur contribution au d\u00e9veloppement \u00e9conomique.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2023\/10\/IMG-51d94a8c3080c526cd2cba6c8ab1fe80-V.jpg\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mme Nassima Meddour, Magistrat \u00e0 la 8e Chambre, participe Aujourd\u2019hui 2 octobre 2023, \u00e0 un webinaire portant sur \u00ab l\u2019am\u00e9lioration [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":7340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-7341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/7341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=7341"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/7341\/revisions"}],"predecessor-version":[{"id":7342,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/7341\/revisions\/7342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/7340"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=7341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=7341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=7341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}