{"id":7809,"date":"2024-02-14T09:29:11","date_gmt":"2024-02-14T08:29:11","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=7809"},"modified":"2024-02-14T09:29:11","modified_gmt":"2024-02-14T08:29:11","slug":"participation-de-la-cour-des-comptes-a-la-59e-reunion-du-comite-directeur-de-lafrosai","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-de-la-cour-des-comptes-a-la-59e-reunion-du-comite-directeur-de-lafrosai\/","title":{"rendered":"Participation de la Cour des comptes \u00e0 la 59e r\u00e9union du Comit\u00e9 directeur de l\u2019AFROSAI"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">Le Pr\u00e9sident de la Cour des comptes, M. Abdelkader BENMAROUF, participe les 8 et 9 f\u00e9vrier 2024 aux travaux de la 59e r\u00e9union du Comit\u00e9 directeur de l\u2019organisation africaine des institutions sup\u00e9rieures de contr\u00f4le (AFROSAI), tenue \u00e0 Yaound\u00e9 &#8211; Cameroun .<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">L\u2019ordre du jour de cette r\u00e9union s\u2019articule autour des points suivants :<\/div>\n<div dir=\"auto\">\u2022 Pr\u00e9sentation des rapports des organes statutaires ;<\/div>\n<div dir=\"auto\">\u2022 Pr\u00e9sentation des rapports des organisations sous r\u00e9gionales ;<\/div>\n<div dir=\"auto\">\u2022 Rapports des organes sp\u00e9cialis\u00e9s ;<\/div>\n<div dir=\"auto\">\u2022 Examen et adoption du plan de travail et budget de l\u2019AFROSAI 2024 ;<\/div>\n<div dir=\"auto\">\u2022 Pr\u00e9sentation des th\u00e8mes techniques de la 16e Assembl\u00e9e g\u00e9n\u00e9rale et du concours scientifique 2024 de l\u2019AFROSAI ;<\/div>\n<div dir=\"auto\">\u2022 R\u00e9flexions sur les modalit\u00e9s de choix du futur si\u00e8ge de l\u2019Organisation ;<\/div>\n<div dir=\"auto\">\u2022 Etat des pr\u00e9paratifs de la 16e Assembl\u00e9e g\u00e9n\u00e9rale.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Par ailleurs, les travaux du Comit\u00e9 directeur ont \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9s, les 5 et 6 f\u00e9vrier 2024, par des sessions de travail des deux (2) commissions techniques de l\u2019AFROSAI, \u00e0 savoir : la Commission de renforcement des capacit\u00e9s institutionnelles et techniques (CRCIT) et la Commission de renforcement des capacit\u00e9s organisationnelles (CRCO). Ces derni\u00e8res ont eu \u00e0 pr\u00e9senter les rapports des groupes de travails et les plans op\u00e9rationnels pour 2024.<\/div>\n<div dir=\"auto\">Le pr\u00e9sident de la Cour des comptes \u00e9tait accompagn\u00e9 de M. Mehdi BOUMEDIEN, Directeur du d\u00e9partement des techniques d\u2019analyse et de contr\u00f4le et de Mme Rym HAMMOUDI, Chef d\u2019\u00e9tudes.<\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/02\/417413010_693724192940321_4101785296321084780_n.jpg\" \/><\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/02\/417552509_693724196273654_1054316010739004868_n.jpg\" \/><\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/02\/417423927_693724186273655_6106051323051675489_n.jpg\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la Cour des comptes, M. Abdelkader BENMAROUF, participe les 8 et 9 f\u00e9vrier 2024 aux travaux de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":7807,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-7809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/7809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=7809"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/7809\/revisions"}],"predecessor-version":[{"id":7810,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/7809\/revisions\/7810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/7807"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=7809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=7809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=7809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}