{"id":8176,"date":"2024-06-06T10:01:08","date_gmt":"2024-06-06T08:01:08","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=8176"},"modified":"2024-06-06T10:01:08","modified_gmt":"2024-06-06T08:01:08","slug":"participation-a-un-atelier-portant-sur-les-charges-de-personnel","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-a-un-atelier-portant-sur-les-charges-de-personnel\/","title":{"rendered":"Participation \u00e0 un atelier portant sur les charges de personnel"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\"><span style=\"font-family: 'times new roman', times, serif;color: #000000\">Dans le cadre de la mise en \u0153uvre du jumelage institutionnel entre la Cour des comptes et ses homologues fran\u00e7aise et portugaise, dix (10) auditeurs et v\u00e9rificateurs financiers, participent aujourd\u2019hui le mardi 04 juin 2024, \u00e0 un atelier portant sur \u00ab l\u2019\u00e9laboration d\u2019un questionnaire relatif au sous-cycle : charges de personnel \u00bb, anim\u00e9 par M. Mickael AZRAN expert en certification \u00e0 la Cour des comptes fran\u00e7aise.<\/span><\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/06\/447395585_760886796224060_773879403773829591_n.jpg\" \/><\/div>\n<div dir=\"auto\"><img decoding=\"async\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/06\/447724883_760886806224059_2327247186382143290_n.jpg\" \/><\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la mise en \u0153uvre du jumelage institutionnel entre la Cour des comptes et ses homologues fran\u00e7aise [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":8177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-8176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=8176"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8176\/revisions"}],"predecessor-version":[{"id":8178,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8176\/revisions\/8178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/8177"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=8176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=8176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=8176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}