{"id":8686,"date":"2024-11-25T14:37:24","date_gmt":"2024-11-25T13:37:24","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=8686"},"modified":"2024-11-25T14:37:24","modified_gmt":"2024-11-25T13:37:24","slug":"participation-a-un-atelier-portant-sur-la-mise-en-oeuvre-du-plan-strategique-et-des-plans-operationnels","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-a-un-atelier-portant-sur-la-mise-en-oeuvre-du-plan-strategique-et-des-plans-operationnels\/","title":{"rendered":"Participation \u00e0 un atelier portant sur la mise en \u0153uvre du plan strat\u00e9gique et des plans op\u00e9rationnels"},"content":{"rendered":"<div dir=\"auto\">Dans le cadre de l\u2019initiative de I&rsquo;IDI sur la gestion strat\u00e9gique, la mesure de la performance et le reporting (SPMR), Mme et M. Djelloul SAFFIH, Pr\u00e9sident de section et Rym HAMMOUDI Chef d\u2019\u00e9tude, membres de l\u2019\u00e9quipe de la gestion strat\u00e9gique, participent du 25 au 29 novembre 2024, \u00e0 un atelier portant sur \u00ab la mise en \u0153uvre du plan strat\u00e9gique et des plans op\u00e9rationnels \u00bb, organis\u00e9 par l\u2019Initiative de d\u00e9veloppement de l\u2019INTOSAI(IDI), \u00e0 Alger.<\/div>\n<div dir=\"auto\">Dix (10) participants repr\u00e9sentant cinq (5) ISC africaines participent aux travaux de cet atelier anim\u00e9 par MM. Laurent Grosse-Kozlowski et Alain MEMVUH, Experts de l\u2019IDI.<\/div>\n<div dir=\"auto\">L\u2019ordre de jour de cet atelier s\u2019articule autour des axes suivants :<\/div>\n<div dir=\"auto\">&#8211; Retour d\u2019exp\u00e9rience sur la planification strat\u00e9gique et op\u00e9rationnelle ;<\/div>\n<div dir=\"auto\">&#8211; \u00c9tablissement des rapports sur la performance ;<\/div>\n<div dir=\"auto\">&#8211; Identification et gestion des Risques ;<\/div>\n<div dir=\"auto\">&#8211; Gestion du changement ;<\/div>\n<div dir=\"auto\">&#8211; \u00c9laboration d\u2019un cadre de suivi de mise en \u0153uvre du plan strat\u00e9gique ;<\/div>\n<div dir=\"auto\">&#8211; \u00c9valuation du cadre de mesure de la performance.<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8685 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/11\/468314219_875426571436748_286213834906718557_n.jpg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468314219_875426571436748_286213834906718557_n.jpg 1080w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468314219_875426571436748_286213834906718557_n-300x225.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468314219_875426571436748_286213834906718557_n-768x576.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468314219_875426571436748_286213834906718557_n-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8683 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/11\/468299693_875426578103414_2482458835876318297_n.jpg\" alt=\"\" width=\"810\" height=\"1080\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468299693_875426578103414_2482458835876318297_n.jpg 810w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468299693_875426578103414_2482458835876318297_n-225x300.jpg 225w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468299693_875426578103414_2482458835876318297_n-768x1024.jpg 768w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8684 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2024\/11\/468334945_875426574770081_9094883274884511633_n.jpg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468334945_875426574770081_9094883274884511633_n.jpg 1080w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468334945_875426574770081_9094883274884511633_n-300x225.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468334945_875426574770081_9094883274884511633_n-768x576.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2024\/11\/468334945_875426574770081_9094883274884511633_n-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de l\u2019initiative de I&rsquo;IDI sur la gestion strat\u00e9gique, la mesure de la performance et le reporting (SPMR), [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":8685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-8686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=8686"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8686\/revisions"}],"predecessor-version":[{"id":8687,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8686\/revisions\/8687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/8685"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=8686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=8686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=8686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}