{"id":8923,"date":"2025-02-12T10:06:32","date_gmt":"2025-02-12T09:06:32","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=8923"},"modified":"2025-02-12T10:06:32","modified_gmt":"2025-02-12T09:06:32","slug":"participation-a-un-seminaire-de-formation-sur-la-certification-des-comptes-de-letat","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/participation-a-un-seminaire-de-formation-sur-la-certification-des-comptes-de-letat\/","title":{"rendered":"Participation \u00e0 un s\u00e9minaire de formation sur la certification des comptes de l&rsquo;\u00c9tat"},"content":{"rendered":"<div dir=\"auto\">Dans le cadre de la mise en \u0153uvre du plan de l&rsquo;Organisation arabe des institutions sup\u00e9rieures de contr\u00f4le des finances publiques (l\u2019ARABOSAI) visant \u00e0 favoriser l&rsquo;\u00e9change d&rsquo;exp\u00e9riences entre les ISC en mati\u00e8re d&rsquo;audit financier, cinq (5) Auditeurs et trois (3) V\u00e9rificateurs financiers participent du 9 au 13 f\u00e9vrier 2025, \u00e0 un s\u00e9minaire \u00e0 distance portant sur :\u00abLa certification des comptes de l&rsquo;\u00c9tat selon les normes et les meilleures pratiques internationales\u00bb, organis\u00e9 par l\u2019ARABOSAI en collaboration avec ISC de de l&rsquo;\u00c9gypte.<\/div>\n<div dir=\"auto\">Ce s\u00e9minaire a pour objectif de fournir un aper\u00e7u g\u00e9n\u00e9ral sur les normes internationales relatives au contr\u00f4le qualit\u00e9, \u00e0 l\u2019audit et aux opinions. Il est \u00e9galement question de la relation entre les normes internationales et les publications de l&rsquo;INTOSAI en mati\u00e8re d&rsquo;audit financier. Ainsi que l&rsquo;application des normes de la certification des comptes de l&rsquo;\u00c9tat, qu&rsquo;ils soient \u00e9tablis selon le principe de la comptabilit\u00e9 de caisse ou de la comptabilit\u00e9 d&rsquo;exercice. En outre, cette rencontre vise \u00e0 \u00e9changer des exp\u00e9riences sur les diff\u00e9rentes \u00e9tapes du processus de planification et d&rsquo;ex\u00e9cution de l&rsquo;audit financier des comptes de l&rsquo;\u00c9tat, ainsi que sur l&rsquo;\u00e9laboration du rapport et le suivi, en mettant l&rsquo;accent sur le contr\u00f4le qualit\u00e9.<\/div>\n<div dir=\"auto\">Ce s\u00e9minaire s\u2019articule autour des axes suivants :<\/div>\n<div dir=\"auto\">\u2022 Le concept de l\u2019audit , ses types et ses objectifs ;<\/div>\n<div dir=\"auto\">\u2022 Une vue d\u2019ensemble sur les normes internationales et leur relation avec les normes de l\u2019INTOSAI ;<\/div>\n<div dir=\"auto\">\u2022 L\u2019application des normes de l\u2019audit des comptes de l\u2019\u00c9tat \u00e9tablis selon la comptabilit\u00e9 de caisse ou la comptabilit\u00e9 d\u2019exercice ;<\/div>\n<div dir=\"auto\">\u2022 Les \u00e9tapes de la mise en \u0153uvre de la certification des comptes de l\u2019\u00c9tat.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8920 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2025\/02\/477250608_928735726105832_5612015162509170694_n.jpg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477250608_928735726105832_5612015162509170694_n.jpg 1080w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477250608_928735726105832_5612015162509170694_n-300x225.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477250608_928735726105832_5612015162509170694_n-768x576.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477250608_928735726105832_5612015162509170694_n-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8921 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2025\/02\/477671781_928735722772499_2998442392786264306_n.jpg\" alt=\"\" width=\"1080\" height=\"810\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477671781_928735722772499_2998442392786264306_n.jpg 1080w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477671781_928735722772499_2998442392786264306_n-300x225.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477671781_928735722772499_2998442392786264306_n-768x576.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477671781_928735722772499_2998442392786264306_n-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8922 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2025\/02\/477173741_928735742772497_6940033861384866509_n.jpg\" alt=\"\" width=\"1366\" height=\"768\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477173741_928735742772497_6940033861384866509_n.jpg 1366w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477173741_928735742772497_6940033861384866509_n-300x169.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477173741_928735742772497_6940033861384866509_n-768x432.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/02\/477173741_928735742772497_6940033861384866509_n-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1366px) 100vw, 1366px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la mise en \u0153uvre du plan de l&rsquo;Organisation arabe des institutions sup\u00e9rieures de contr\u00f4le des finances [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":8922,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-8923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=8923"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8923\/revisions"}],"predecessor-version":[{"id":8924,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/8923\/revisions\/8924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/8922"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=8923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=8923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=8923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}