{"id":9002,"date":"2025-03-20T13:39:57","date_gmt":"2025-03-20T12:39:57","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=9002"},"modified":"2025-03-20T13:39:57","modified_gmt":"2025-03-20T12:39:57","slug":"reunion-du-comite-des-programmes-et-des-rapports-48","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/reunion-du-comite-des-programmes-et-des-rapports-48\/","title":{"rendered":"R\u00e9union du Comit\u00e9 des programmes et des rapports"},"content":{"rendered":"<div class=\"xdj266r x11i5rnm xat24cr x1mh8g0r x1vvkbs x126k92a\">\n<div dir=\"auto\">Le Comit\u00e9 des programmes et des rapports se r\u00e9unit, aujourd\u2019hui jeudi 20 mars 2025 par visioconf\u00e9rence, sous la pr\u00e9sidence de M. Mohamed Fouad NACIR, Charg\u00e9 de la gestion des affaires de la Cour des comptes, en vue de l\u2019examen et de l\u2019adoption d\u2019un projet de note d\u2019insertion au rapport annuel 2025, pr\u00e9sent\u00e9 par la 1e Chambre.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div dir=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9001 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2025\/03\/484956158_955879403391464_4416277257623481962_n.jpg\" alt=\"\" width=\"1627\" height=\"922\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/03\/484956158_955879403391464_4416277257623481962_n.jpg 1627w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/03\/484956158_955879403391464_4416277257623481962_n-300x170.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/03\/484956158_955879403391464_4416277257623481962_n-768x435.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/03\/484956158_955879403391464_4416277257623481962_n-1024x580.jpg 1024w\" sizes=\"auto, (max-width: 1627px) 100vw, 1627px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le Comit\u00e9 des programmes et des rapports se r\u00e9unit, aujourd\u2019hui jeudi 20 mars 2025 par visioconf\u00e9rence, sous la pr\u00e9sidence de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9001,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/9002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=9002"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/9002\/revisions"}],"predecessor-version":[{"id":9003,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/9002\/revisions\/9003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/9001"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=9002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=9002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=9002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}