{"id":9500,"date":"2025-07-03T15:19:38","date_gmt":"2025-07-03T13:19:38","guid":{"rendered":"https:\/\/www.ccomptes.dz\/?p=9500"},"modified":"2025-07-03T15:19:38","modified_gmt":"2025-07-03T13:19:38","slug":"reunion-du-comite-des-programmes-et-des-rapports-62","status":"publish","type":"post","link":"https:\/\/ccomptes.dz\/fr\/actualite\/reunion-du-comite-des-programmes-et-des-rapports-62\/","title":{"rendered":"R\u00e9union du Comit\u00e9 des programmes et des rapports"},"content":{"rendered":"<p>Le Comit\u00e9 des programmes et des rapports s\u2019est r\u00e9uni aujourd\u2019hui, jeudi 3 juillet 2025, par visioconf\u00e9rence, sous la pr\u00e9sidence de M. Mohamed Fouad NACIR, Charg\u00e9 de la gestion des affaires de la Cour des comptes, en vue de l\u2019examen et de l\u2019adoption de deux projets de notes d\u2019insertion au rapport annuel 2025, pr\u00e9sent\u00e9s par les Chambres territoriales de Annaba et de Constantine.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9501 size-full\" src=\"https:\/\/www.ccomptes.dz\/wp-content\/uploads\/2025\/07\/cpr.jpg\" alt=\"\" width=\"1670\" height=\"646\" srcset=\"https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/07\/cpr.jpg 1670w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/07\/cpr-300x116.jpg 300w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/07\/cpr-768x297.jpg 768w, https:\/\/ccomptes.dz\/wp-content\/uploads\/2025\/07\/cpr-1024x396.jpg 1024w\" sizes=\"auto, (max-width: 1670px) 100vw, 1670px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Comit\u00e9 des programmes et des rapports s\u2019est r\u00e9uni aujourd\u2019hui, jeudi 3 juillet 2025, par visioconf\u00e9rence, sous la pr\u00e9sidence de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9501,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9500","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/9500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/comments?post=9500"}],"version-history":[{"count":1,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/9500\/revisions"}],"predecessor-version":[{"id":9502,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/posts\/9500\/revisions\/9502"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media\/9501"}],"wp:attachment":[{"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/media?parent=9500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/categories?post=9500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccomptes.dz\/fr\/wp-json\/wp\/v2\/tags?post=9500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}